{"id":141,"count":6,"description":"","link":"https:\/\/369agara.com\/en\/product-category\/musique-des-plantes\/","name":"Plant music","slug":"musique-des-plantes","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":14,"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Archives des Musique des plantes | Agara<\/title>\n<meta name=\"description\" content=\"Vous trouverez ici des produits sur la Musique des Plantes et du mat\u00e9riel pour pratiquer les soins bien-\u00eatre par la musique des plantes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/369agara.com\/en\/product-category\/musique-des-plantes\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Musique des plantes\" \/>\n<meta property=\"og:description\" content=\"Vous trouverez ici des produits sur la Musique des Plantes et du mat\u00e9riel pour pratiquer les soins bien-\u00eatre par la musique des plantes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/369agara.com\/en\/product-category\/musique-des-plantes\/\" \/>\n<meta property=\"og:site_name\" content=\"Agara\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/369agara.com\\\/product-category\\\/musique-des-plantes\\\/\",\"url\":\"https:\\\/\\\/369agara.com\\\/product-category\\\/musique-des-plantes\\\/\",\"name\":\"Archives des Musique des plantes | Agara\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/369agara.com\\\/#website\"},\"description\":\"Vous trouverez ici des produits sur la Musique des Plantes et du mat\u00e9riel pour pratiquer les soins bien-\u00eatre par la musique des plantes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/369agara.com\\\/product-category\\\/musique-des-plantes\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/369agara.com\\\/product-category\\\/musique-des-plantes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/369agara.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Musique des plantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/369agara.com\\\/#website\",\"url\":\"https:\\\/\\\/369agara.com\\\/\",\"name\":\"Livsrikedomar\",\"description\":\"D\u00e9connectez pour mieux vous connecter\",\"publisher\":{\"@id\":\"https:\\\/\\\/369agara.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/369agara.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/369agara.com\\\/#organization\",\"name\":\"EACreations\",\"url\":\"https:\\\/\\\/369agara.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/369agara.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"EACreations\"},\"image\":{\"@id\":\"https:\\\/\\\/369agara.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Archives des Musique des plantes | Agara","description":"Vous trouverez ici des produits sur la Musique des Plantes et du mat\u00e9riel pour pratiquer les soins bien-\u00eatre par la musique des plantes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/369agara.com\/en\/product-category\/musique-des-plantes\/","og_locale":"en_GB","og_type":"article","og_title":"Archives des Musique des plantes","og_description":"Vous trouverez ici des produits sur la Musique des Plantes et du mat\u00e9riel pour pratiquer les soins bien-\u00eatre par la musique des plantes.","og_url":"https:\/\/369agara.com\/en\/product-category\/musique-des-plantes\/","og_site_name":"Agara","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/369agara.com\/product-category\/musique-des-plantes\/","url":"https:\/\/369agara.com\/product-category\/musique-des-plantes\/","name":"Archives des Musique des plantes | Agara","isPartOf":{"@id":"https:\/\/369agara.com\/#website"},"description":"Vous trouverez ici des produits sur la Musique des Plantes et du mat\u00e9riel pour pratiquer les soins bien-\u00eatre par la musique des plantes.","breadcrumb":{"@id":"https:\/\/369agara.com\/product-category\/musique-des-plantes\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/369agara.com\/product-category\/musique-des-plantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/369agara.com\/"},{"@type":"ListItem","position":2,"name":"Musique des plantes"}]},{"@type":"WebSite","@id":"https:\/\/369agara.com\/#website","url":"https:\/\/369agara.com\/","name":"Livsrikedomar","description":"Disconnect to better connect","publisher":{"@id":"https:\/\/369agara.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/369agara.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/369agara.com\/#organization","name":"EACreations","url":"https:\/\/369agara.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/369agara.com\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"EACreations"},"image":{"@id":"https:\/\/369agara.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/369agara.com\/en\/wp-json\/wp\/v2\/product_cat\/141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/369agara.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/369agara.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/369agara.com\/en\/wp-json\/wp\/v2\/product?product_cat=141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}